{"id":916,"date":"2023-10-11T13:50:38","date_gmt":"2023-10-11T11:50:38","guid":{"rendered":"http:\/\/digama.wp4.mtncompany.cloud\/?page_id=916"},"modified":"2025-04-10T15:06:34","modified_gmt":"2025-04-10T13:06:34","slug":"elevatore-a-tazze","status":"publish","type":"page","link":"https:\/\/www.meccanicadigama.com\/it\/elevatore-a-tazze\/","title":{"rendered":"Elevatore a tazze"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-lnlofh8f-d1f9d2b1f3a10ee82b79c9ba3410abed\">\n#top .av-special-heading.av-lnlofh8f-d1f9d2b1f3a10ee82b79c9ba3410abed{\npadding-bottom:10px;\nfont-size:32px;\n}\nbody .av-special-heading.av-lnlofh8f-d1f9d2b1f3a10ee82b79c9ba3410abed .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n#top #wrap_all .av-special-heading.av-lnlofh8f-d1f9d2b1f3a10ee82b79c9ba3410abed .av-special-heading-tag{\nfont-size:32px;\n}\n.av-special-heading.av-lnlofh8f-d1f9d2b1f3a10ee82b79c9ba3410abed .av-subheading{\nfont-size:15px;\n}\n\n@media only screen and (min-width: 480px) and (max-width: 767px){ \n#top #wrap_all .av-special-heading.av-lnlofh8f-d1f9d2b1f3a10ee82b79c9ba3410abed .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n\n@media only screen and (max-width: 479px){ \n#top #wrap_all .av-special-heading.av-lnlofh8f-d1f9d2b1f3a10ee82b79c9ba3410abed .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n<\/style>\n<div  class='av-special-heading av-lnlofh8f-d1f9d2b1f3a10ee82b79c9ba3410abed av-special-heading-h1 blockquote modern-quote  avia-builder-el-0  el_before_av_slideshow  avia-builder-el-first  av-thin-font av-inherit-size'><h1 class='av-special-heading-tag'  itemprop=\"headline\"  ><strong>Elevatore a tazze<\/strong><\/h1><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n<div  class='avia-slideshow av-lnloisxd-5d525bfdea4d6a29a93003b48aa6ffed avia-slideshow-featured_large av_slideshow avia-slide-slider  avia-builder-el-1  el_after_av_heading  el_before_av_textblock  av-slideshow-ui av-control-default av-nav-arrows-visible av-nav-dots-visible av-slideshow-manual av-loop-once av-loop-manual-endless av-default-height-applied avia-slideshow-1' data-slideshow-options=\"{&quot;animation&quot;:&quot;slide&quot;,&quot;autoplay&quot;:false,&quot;loop_autoplay&quot;:&quot;once&quot;,&quot;interval&quot;:5,&quot;loop_manual&quot;:&quot;manual-endless&quot;,&quot;autoplay_stopper&quot;:false,&quot;noNavigation&quot;:false,&quot;bg_slider&quot;:false,&quot;keep_padding&quot;:false,&quot;hoverpause&quot;:false,&quot;show_slide_delay&quot;:0}\"  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><ul class='avia-slideshow-inner ' style='padding-bottom: 60.460652591171%;'><li  class='avia-slideshow-slide av-lnloisxd-5d525bfdea4d6a29a93003b48aa6ffed__0  av-single-slide slide-1 slide-odd'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" class=\"wp-image-918 avia-img-lazy-loading-not-918\"  src=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/Digama_elevatore-a-tazze-1042x630.jpg\" width=\"1042\" height=\"630\" title='Digama_elevatore-a-tazze' alt=''  itemprop=\"thumbnailUrl\"   \/><\/div><\/li><\/ul><\/div>\n<section  class='av_textblock_section av-lnloh60s-8dfaef4ffbb5aa7c89ae651712cf482f '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p class=\"Textbody\"><span style=\"font-family: Roboto;\">L\u2019elevatore a tazze \u00e8 costruito per spostare legumi o alimenti simili da una quota ad un\u2019altra in direzione verticale. <\/span><\/p>\n<p class=\"Textbody\"><span style=\"font-family: Roboto;\">Le dimensioni posso variare a seconda delle esigenze<\/span><\/p>\n<\/div><\/section>\n<div  class='hr av-gal7n-f780fc0d1c9e3779ca75b04d82eef87a hr-default  avia-builder-el-3  el_after_av_textblock  el_before_av_textblock '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n<section  class='av_textblock_section av-afmaz-de33db9b0a2adb8ebc57d0809d61965d '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" >\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f402-o1\" lang=\"it-IT\" dir=\"ltr\" data-wpcf7-id=\"402\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/it\/wp-json\/wp\/v2\/pages\/916#wpcf7-f402-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Modulo di contatto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"402\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.3\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"it_IT\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f402-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<h2 class=\"head-form\">Personalizza il macchinario secondo le tue esigenze.<br \/>\nContattaci!\n<\/h2>\n<p><span id=\"wpcf7-6a049e91aeabb-wrapper\" class=\"wpcf7-form-control-wrap azienda-wrap\" style=\"display:none !important; visibility:hidden !important;\"><label for=\"azienda\" class=\"hp-message\">Si prega di lasciare vuoto questo campo.<\/label><input id=\"azienda\"  class=\"wpcf7-form-control wpcf7-text\" type=\"text\" name=\"azienda\" value=\"\" size=\"40\" tabindex=\"-1\" autocomplete=\"new-password\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nome\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-surname\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"surname\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Cognome\" value=\"\" type=\"text\" name=\"your-surname\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-tel\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Telefono\" value=\"\" type=\"tel\" name=\"your-tel\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Il tuo messaggio\" name=\"your-message\"><\/textarea><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-152\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"acceptance-152\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">Dichiaro di aver letto attentamente e compreso il contenuto della\u00a0<a href=\"\/privacy-policy\/\" target=\"_blank\" rel=\"noopener\">Privacy Policy<\/a>\u00a0relativamente alle finalit\u00e0 perseguite tramite l'acquisizione dei dati personali necessari all\u2019esecuzione delle prestazioni oggetto del servizio erogato.<\/span><\/label><\/span><\/span><\/span>\n<\/p>\n<p><input type=\"hidden\" name=\"_wpcf7_captcha_challenge_captcha-1\" value=\"1886555015\" \/><img loading=\"lazy\" decoding=\"async\" class=\"wpcf7-form-control wpcf7-captchac wpcf7-captcha-captcha-1\" width=\"72\" height=\"24\" alt=\"captcha\" src=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/wpcf7_captcha\/1886555015.png\" \/><span class=\"wpcf7-form-control-wrap\" data-name=\"captcha-1\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-captchar\" autocomplete=\"off\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"captcha-1\" \/><\/span><br \/>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" id=\"sendform\" type=\"submit\" value=\"Contattaci\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n<\/div><\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":10,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-916","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Elevatore a tazze - Meccanica Digama<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.meccanicadigama.com\/it\/elevatore-a-tazze\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elevatore a tazze - Meccanica Digama\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.meccanicadigama.com\/it\/elevatore-a-tazze\/\" \/>\n<meta property=\"og:site_name\" content=\"Meccanica Digama\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-10T13:06:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.meccanicadigama.com\/it\/elevatore-a-tazze\/\",\"url\":\"https:\/\/www.meccanicadigama.com\/it\/elevatore-a-tazze\/\",\"name\":\"Elevatore a tazze - Meccanica Digama\",\"isPartOf\":{\"@id\":\"https:\/\/www.meccanicadigama.com\/it\/#website\"},\"datePublished\":\"2023-10-11T11:50:38+00:00\",\"dateModified\":\"2025-04-10T13:06:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.meccanicadigama.com\/it\/elevatore-a-tazze\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.meccanicadigama.com\/it\/elevatore-a-tazze\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.meccanicadigama.com\/it\/elevatore-a-tazze\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.meccanicadigama.com\/it\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elevatore a tazze\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.meccanicadigama.com\/it\/#website\",\"url\":\"https:\/\/www.meccanicadigama.com\/it\/\",\"name\":\"Meccanica Digama\",\"description\":\"Macchine per l&#039;industria alimentare\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.meccanicadigama.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elevatore a tazze - Meccanica Digama","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.meccanicadigama.com\/it\/elevatore-a-tazze\/","og_locale":"it_IT","og_type":"article","og_title":"Elevatore a tazze - Meccanica Digama","og_url":"https:\/\/www.meccanicadigama.com\/it\/elevatore-a-tazze\/","og_site_name":"Meccanica Digama","article_modified_time":"2025-04-10T13:06:34+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.meccanicadigama.com\/it\/elevatore-a-tazze\/","url":"https:\/\/www.meccanicadigama.com\/it\/elevatore-a-tazze\/","name":"Elevatore a tazze - Meccanica Digama","isPartOf":{"@id":"https:\/\/www.meccanicadigama.com\/it\/#website"},"datePublished":"2023-10-11T11:50:38+00:00","dateModified":"2025-04-10T13:06:34+00:00","breadcrumb":{"@id":"https:\/\/www.meccanicadigama.com\/it\/elevatore-a-tazze\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.meccanicadigama.com\/it\/elevatore-a-tazze\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.meccanicadigama.com\/it\/elevatore-a-tazze\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.meccanicadigama.com\/it\/home\/"},{"@type":"ListItem","position":2,"name":"Elevatore a tazze"}]},{"@type":"WebSite","@id":"https:\/\/www.meccanicadigama.com\/it\/#website","url":"https:\/\/www.meccanicadigama.com\/it\/","name":"Meccanica Digama","description":"Macchine per l&#039;industria alimentare","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.meccanicadigama.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.meccanicadigama.com\/it\/wp-json\/wp\/v2\/pages\/916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.meccanicadigama.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.meccanicadigama.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.meccanicadigama.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.meccanicadigama.com\/it\/wp-json\/wp\/v2\/comments?post=916"}],"version-history":[{"count":12,"href":"https:\/\/www.meccanicadigama.com\/it\/wp-json\/wp\/v2\/pages\/916\/revisions"}],"predecessor-version":[{"id":4124,"href":"https:\/\/www.meccanicadigama.com\/it\/wp-json\/wp\/v2\/pages\/916\/revisions\/4124"}],"wp:attachment":[{"href":"https:\/\/www.meccanicadigama.com\/it\/wp-json\/wp\/v2\/media?parent=916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}