{"id":1647,"date":"2023-10-12T13:50:06","date_gmt":"2023-10-12T11:50:06","guid":{"rendered":"http:\/\/digama.wp4.mtncompany.cloud\/?page_id=1647"},"modified":"2023-10-20T09:33:56","modified_gmt":"2023-10-20T07:33:56","slug":"robot-pallettizzatore-con-testata-aspirante","status":"publish","type":"page","link":"https:\/\/www.meccanicadigama.com\/it\/robot-pallettizzatore-con-testata-aspirante\/","title":{"rendered":"Robot Pallettizzatore con testata aspirante &#8211; Robot"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-lnn17bzn-94ee34c956e7337c3dd7e433c21edfe4\">\n#top .av-special-heading.av-lnn17bzn-94ee34c956e7337c3dd7e433c21edfe4{\npadding-bottom:10px;\nfont-size:32px;\n}\nbody .av-special-heading.av-lnn17bzn-94ee34c956e7337c3dd7e433c21edfe4 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n#top #wrap_all .av-special-heading.av-lnn17bzn-94ee34c956e7337c3dd7e433c21edfe4 .av-special-heading-tag{\nfont-size:32px;\n}\n.av-special-heading.av-lnn17bzn-94ee34c956e7337c3dd7e433c21edfe4 .av-subheading{\nfont-size:15px;\n}\n\n@media only screen and (min-width: 480px) and (max-width: 767px){ \n#top #wrap_all .av-special-heading.av-lnn17bzn-94ee34c956e7337c3dd7e433c21edfe4 .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n\n@media only screen and (max-width: 479px){ \n#top #wrap_all .av-special-heading.av-lnn17bzn-94ee34c956e7337c3dd7e433c21edfe4 .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n<\/style>\n<div  class='av-special-heading av-lnn17bzn-94ee34c956e7337c3dd7e433c21edfe4 av-special-heading-h1 blockquote modern-quote  avia-builder-el-0  el_before_av_slideshow  avia-builder-el-first  av-thin-font av-inherit-size'><h1 class='av-special-heading-tag'  itemprop=\"headline\"  ><strong>Robot Pallettizzatore con testata aspirante<\/strong><\/h1><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n<div  class='avia-slideshow av-lnn1dyfm-42cbd6e181a86e883290fa477ccb304f avia-slideshow-featured_large av_slideshow avia-slide-slider  avia-builder-el-1  el_after_av_heading  el_before_av_textblock  av-slideshow-ui av-control-default av-slideshow-manual av-loop-once av-loop-manual-endless av-default-height-applied avia-slideshow-1' data-slideshow-options=\"{&quot;animation&quot;:&quot;slide&quot;,&quot;autoplay&quot;:false,&quot;loop_autoplay&quot;:&quot;once&quot;,&quot;interval&quot;:5,&quot;loop_manual&quot;:&quot;manual-endless&quot;,&quot;autoplay_stopper&quot;:false,&quot;noNavigation&quot;:false,&quot;bg_slider&quot;:false,&quot;keep_padding&quot;:false,&quot;hoverpause&quot;:false,&quot;show_slide_delay&quot;:0}\"  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><ul class='avia-slideshow-inner ' style='padding-bottom: 42%;'><li  class='avia-slideshow-slide av-lnn1dyfm-42cbd6e181a86e883290fa477ccb304f__0  slide-1 slide-odd'><a href=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-1-1030x686.jpg\" data-srcset=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-1-1030x686.jpg 1030w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-1-300x200.jpg 300w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-1-768x512.jpg 768w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-1-1536x1024.jpg 1536w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-1-1500x1000.jpg 1500w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-1-705x470.jpg 705w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-1.jpg 2048w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" class=\"wp-image-1587 avia-img-lazy-loading-not-1587\"  src=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-1-1500x630.jpg\" width=\"1500\" height=\"630\" title='robot-depal-2.0-1' alt=''  itemprop=\"thumbnailUrl\"   \/><\/a><\/li><li  class='avia-slideshow-slide av-lnn1dyfm-42cbd6e181a86e883290fa477ccb304f__1  slide-2 slide-even'><a href=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-2-1030x686.jpg\" data-srcset=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-2-1030x686.jpg 1030w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-2-300x200.jpg 300w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-2-768x512.jpg 768w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-2-1536x1024.jpg 1536w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-2-1500x1000.jpg 1500w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-2-705x470.jpg 705w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-2.jpg 2048w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" class=\"wp-image-1590 avia-img-lazy-loading-not-1590\"  src=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-2-1500x630.jpg\" width=\"1500\" height=\"630\" title='robot-depal-2.0-2' alt=''  itemprop=\"thumbnailUrl\"   \/><\/a><\/li><li  class='avia-slideshow-slide av-lnn1dyfm-42cbd6e181a86e883290fa477ccb304f__2  slide-3 slide-odd'><a href=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-3-1030x686.jpg\" data-srcset=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-3-1030x686.jpg 1030w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-3-300x200.jpg 300w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-3-768x512.jpg 768w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-3-1536x1024.jpg 1536w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-3-1500x1000.jpg 1500w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-3-705x470.jpg 705w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-3.jpg 2048w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" class=\"wp-image-1593 avia-img-lazy-loading-not-1593\"  src=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-3-1500x630.jpg\" width=\"1500\" height=\"630\" title='robot-depal-2.0-3' alt=''  itemprop=\"thumbnailUrl\"   \/><\/a><\/li><li  class='avia-slideshow-slide av-lnn1dyfm-42cbd6e181a86e883290fa477ccb304f__3  slide-4 slide-even'><a href=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-4-1030x686.jpg\" data-srcset=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-4-1030x686.jpg 1030w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-4-300x200.jpg 300w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-4-768x512.jpg 768w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-4-1536x1024.jpg 1536w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-4-1500x1000.jpg 1500w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-4-705x470.jpg 705w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-4.jpg 2048w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" class=\"wp-image-1596 avia-img-lazy-loading-not-1596\"  src=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-4-1500x630.jpg\" width=\"1500\" height=\"630\" title='robot-depal-2.0-4' alt=''  itemprop=\"thumbnailUrl\"   \/><\/a><\/li><li  class='avia-slideshow-slide av-lnn1dyfm-42cbd6e181a86e883290fa477ccb304f__4  slide-5 slide-odd'><a href=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-5-1030x686.jpg\" data-srcset=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-5-1030x686.jpg 1030w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-5-300x200.jpg 300w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-5-768x512.jpg 768w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-5-1536x1024.jpg 1536w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-5-1500x1000.jpg 1500w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-5-705x470.jpg 705w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-5.jpg 2048w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" class=\"wp-image-1599 avia-img-lazy-loading-not-1599\"  src=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-5-1500x630.jpg\" width=\"1500\" height=\"630\" title='robot-depal-2.0-5' alt=''  itemprop=\"thumbnailUrl\"   \/><\/a><\/li><li  class='avia-slideshow-slide av-lnn1dyfm-42cbd6e181a86e883290fa477ccb304f__5  slide-6 slide-even'><a href=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-6-1030x686.jpg\" data-srcset=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-6-1030x686.jpg 1030w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-6-300x200.jpg 300w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-6-768x512.jpg 768w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-6-1536x1024.jpg 1536w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-6-1500x1000.jpg 1500w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-6-705x470.jpg 705w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-6.jpg 2048w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" class=\"wp-image-1602 avia-img-lazy-loading-not-1602\"  src=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-6-1500x630.jpg\" width=\"1500\" height=\"630\" title='robot-depal-2.0-6' alt=''  itemprop=\"thumbnailUrl\"   \/><\/a><\/li><li  class='avia-slideshow-slide av-lnn1dyfm-42cbd6e181a86e883290fa477ccb304f__6  slide-7 slide-odd'><a href=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-7-1030x686.jpg\" data-srcset=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-7-1030x686.jpg 1030w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-7-300x200.jpg 300w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-7-768x512.jpg 768w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-7-1536x1024.jpg 1536w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-7-1500x1000.jpg 1500w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-7-705x470.jpg 705w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-7.jpg 2048w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" class=\"wp-image-1605 avia-img-lazy-loading-not-1605\"  src=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-7-1500x630.jpg\" width=\"1500\" height=\"630\" title='robot-depal-2.0-7' alt=''  itemprop=\"thumbnailUrl\"   \/><\/a><\/li><li  class='avia-slideshow-slide av-lnn1dyfm-42cbd6e181a86e883290fa477ccb304f__7  slide-8 slide-even'><a href=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-8-1030x686.jpg\" data-srcset=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-8-1030x686.jpg 1030w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-8-300x200.jpg 300w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-8-768x512.jpg 768w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-8-1536x1024.jpg 1536w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-8-1500x1000.jpg 1500w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-8-705x470.jpg 705w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-8.jpg 2048w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" class=\"wp-image-1608 avia-img-lazy-loading-not-1608\"  src=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-8-1500x630.jpg\" width=\"1500\" height=\"630\" title='robot-depal-2.0-8' alt=''  itemprop=\"thumbnailUrl\"   \/><\/a><\/li><li  class='avia-slideshow-slide av-lnn1dyfm-42cbd6e181a86e883290fa477ccb304f__8  slide-9 slide-odd'><a href=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-9-686x1030.jpg\" data-srcset=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-9-686x1030.jpg 686w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-9-200x300.jpg 200w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-9-768x1152.jpg 768w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-9-1024x1536.jpg 1024w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-9-1000x1500.jpg 1000w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-9-470x705.jpg 470w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-9.jpg 1365w\" data-sizes=\"(max-width: 686px) 100vw, 686px\"  data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" class=\"wp-image-1611 avia-img-lazy-loading-not-1611\"  src=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-9-1365x630.jpg\" width=\"1365\" height=\"630\" title='robot-depal-2.0-9' alt=''  itemprop=\"thumbnailUrl\"   \/><\/a><\/li><li  class='avia-slideshow-slide av-lnn1dyfm-42cbd6e181a86e883290fa477ccb304f__9  slide-10 slide-even'><a href=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-10-1030x686.jpg\" data-srcset=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-10-1030x686.jpg 1030w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-10-300x200.jpg 300w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-10-768x512.jpg 768w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-10-1536x1024.jpg 1536w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-10-1500x1000.jpg 1500w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-10-705x470.jpg 705w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-10.jpg 2048w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" class=\"wp-image-1614 avia-img-lazy-loading-not-1614\"  src=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-10-1500x630.jpg\" width=\"1500\" height=\"630\" title='robot-depal-2.0-10' alt=''  itemprop=\"thumbnailUrl\"   \/><\/a><\/li><li  class='avia-slideshow-slide av-lnn1dyfm-42cbd6e181a86e883290fa477ccb304f__10  slide-11 slide-odd'><a href=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-11-1030x686.jpg\" data-srcset=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-11-1030x686.jpg 1030w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-11-300x200.jpg 300w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-11-768x512.jpg 768w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-11-1536x1024.jpg 1536w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-11-1500x1000.jpg 1500w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-11-705x470.jpg 705w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-11.jpg 2048w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" class=\"wp-image-1617 avia-img-lazy-loading-not-1617\"  src=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-11-1500x630.jpg\" width=\"1500\" height=\"630\" title='robot-depal-2.0-11' alt=''  itemprop=\"thumbnailUrl\"   \/><\/a><\/li><li  class='avia-slideshow-slide av-lnn1dyfm-42cbd6e181a86e883290fa477ccb304f__11  slide-12 slide-even'><a href=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-12-1030x686.jpg\" data-srcset=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-12-1030x686.jpg 1030w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-12-300x200.jpg 300w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-12-768x512.jpg 768w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-12-1536x1024.jpg 1536w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-12-1500x1000.jpg 1500w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-12-705x470.jpg 705w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-12.jpg 2048w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" class=\"wp-image-1620 avia-img-lazy-loading-not-1620\"  src=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-12-1500x630.jpg\" width=\"1500\" height=\"630\" title='robot-depal-2.0-12' alt=''  itemprop=\"thumbnailUrl\"   \/><\/a><\/li><li  class='avia-slideshow-slide av-lnn1dyfm-42cbd6e181a86e883290fa477ccb304f__12  slide-13 slide-odd'><a href=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-13-1030x686.jpg\" data-srcset=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-13-1030x686.jpg 1030w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-13-300x200.jpg 300w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-13-768x512.jpg 768w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-13-1536x1024.jpg 1536w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-13-1500x1000.jpg 1500w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-13-705x470.jpg 705w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-13.jpg 2048w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" class=\"wp-image-1623 avia-img-lazy-loading-not-1623\"  src=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-13-1500x630.jpg\" width=\"1500\" height=\"630\" title='robot-depal-2.0-13' alt=''  itemprop=\"thumbnailUrl\"   \/><\/a><\/li><li  class='avia-slideshow-slide av-lnn1dyfm-42cbd6e181a86e883290fa477ccb304f__13  slide-14 slide-even'><a href=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-14-1030x686.jpg\" data-srcset=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-14-1030x686.jpg 1030w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-14-300x200.jpg 300w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-14-768x512.jpg 768w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-14-1536x1024.jpg 1536w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-14-1500x1000.jpg 1500w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-14-705x470.jpg 705w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-14.jpg 2048w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" class=\"wp-image-1626 avia-img-lazy-loading-not-1626\"  src=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-14-1500x630.jpg\" width=\"1500\" height=\"630\" title='robot-depal-2.0-14' alt=''  itemprop=\"thumbnailUrl\"   \/><\/a><\/li><li  class='avia-slideshow-slide av-lnn1dyfm-42cbd6e181a86e883290fa477ccb304f__14  slide-15 slide-odd'><a href=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-15-1030x686.jpg\" data-srcset=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-15-1030x686.jpg 1030w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-15-300x200.jpg 300w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-15-768x512.jpg 768w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-15-1536x1024.jpg 1536w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-15-1500x1000.jpg 1500w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-15-705x470.jpg 705w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-15.jpg 2048w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" class=\"wp-image-1629 avia-img-lazy-loading-not-1629\"  src=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-15-1500x630.jpg\" width=\"1500\" height=\"630\" title='robot-depal-2.0-15' alt=''  itemprop=\"thumbnailUrl\"   \/><\/a><\/li><li  class='avia-slideshow-slide av-lnn1dyfm-42cbd6e181a86e883290fa477ccb304f__15  slide-16 slide-even'><a href=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-16-1030x686.jpg\" data-srcset=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-16-1030x686.jpg 1030w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-16-300x200.jpg 300w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-16-768x512.jpg 768w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-16-1536x1024.jpg 1536w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-16-1500x1000.jpg 1500w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-16-705x470.jpg 705w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-16.jpg 2048w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" class=\"wp-image-1632 avia-img-lazy-loading-not-1632\"  src=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-16-1500x630.jpg\" width=\"1500\" height=\"630\" title='robot-depal-2.0-16' alt=''  itemprop=\"thumbnailUrl\"   \/><\/a><\/li><li  class='avia-slideshow-slide av-lnn1dyfm-42cbd6e181a86e883290fa477ccb304f__16  slide-17 slide-odd'><a href=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-17-1030x686.jpg\" data-srcset=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-17-1030x686.jpg 1030w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-17-300x200.jpg 300w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-17-768x512.jpg 768w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-17-1536x1024.jpg 1536w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-17-1500x1000.jpg 1500w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-17-705x470.jpg 705w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-17.jpg 2048w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" class=\"wp-image-1635 avia-img-lazy-loading-not-1635\"  src=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-17-1500x630.jpg\" width=\"1500\" height=\"630\" title='robot-depal-2.0-17' alt=''  itemprop=\"thumbnailUrl\"   \/><\/a><\/li><li  class='avia-slideshow-slide av-lnn1dyfm-42cbd6e181a86e883290fa477ccb304f__17  slide-18 slide-even'><a href=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-18-1030x686.jpg\" data-srcset=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-18-1030x686.jpg 1030w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-18-300x200.jpg 300w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-18-768x512.jpg 768w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-18-1536x1024.jpg 1536w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-18-1500x1000.jpg 1500w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-18-705x470.jpg 705w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-18.jpg 2048w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" class=\"wp-image-1638 avia-img-lazy-loading-not-1638\"  src=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-18-1500x630.jpg\" width=\"1500\" height=\"630\" title='robot-depal-2.0-18' alt=''  itemprop=\"thumbnailUrl\"   \/><\/a><\/li><li  class='avia-slideshow-slide av-lnn1dyfm-42cbd6e181a86e883290fa477ccb304f__18  slide-19 slide-odd'><a href=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-19-1030x686.jpg\" data-srcset=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-19-1030x686.jpg 1030w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-19-300x200.jpg 300w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-19-768x512.jpg 768w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-19-1536x1024.jpg 1536w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-19-1500x1000.jpg 1500w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-19-705x470.jpg 705w, https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-19.jpg 2048w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" class=\"wp-image-1641 avia-img-lazy-loading-not-1641\"  src=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/2023\/10\/robot-depal-2.0-19-1500x630.jpg\" width=\"1500\" height=\"630\" title='robot-depal-2.0-19' alt=''  itemprop=\"thumbnailUrl\"   \/><\/a><\/li><\/ul><div class='avia-slideshow-arrows avia-slideshow-controls' ><a href='#prev' class='prev-slide ' aria-hidden='true' data-av_icon='\ue87c' data-av_iconfont='entypo-fontello'  tabindex='-1'>Prec<\/a><a href='#next' class='next-slide ' aria-hidden='true' data-av_icon='\ue87d' data-av_iconfont='entypo-fontello'  tabindex='-1'>Succ<\/a><\/div><div class='avia-slideshow-dots avia-slideshow-controls'><a href='#1' class='goto-slide active' >1<\/a><a href='#2' class='goto-slide ' >2<\/a><a href='#3' class='goto-slide ' >3<\/a><a href='#4' class='goto-slide ' >4<\/a><a href='#5' class='goto-slide ' >5<\/a><a href='#6' class='goto-slide ' >6<\/a><a href='#7' class='goto-slide ' >7<\/a><a href='#8' class='goto-slide ' >8<\/a><a href='#9' class='goto-slide ' >9<\/a><a href='#10' class='goto-slide ' >10<\/a><a href='#11' class='goto-slide ' >11<\/a><a href='#12' class='goto-slide ' >12<\/a><a href='#13' class='goto-slide ' >13<\/a><a href='#14' class='goto-slide ' >14<\/a><a href='#15' class='goto-slide ' >15<\/a><a href='#16' class='goto-slide ' >16<\/a><a href='#17' class='goto-slide ' >17<\/a><a href='#18' class='goto-slide ' >18<\/a><a href='#19' class='goto-slide ' >19<\/a><\/div><\/div>\n<section  class='av_textblock_section av-lnn16un5-dadc8b4cd6fd9d7d298173d9cdcc00c4 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock boxed'  itemprop=\"text\" ><p><strong><em>Industria 4.0<\/em><\/strong><br \/>\n<em>Il robot Digama risponde ai requisiti richiesti dal\u00a0nuovo\u00a0<strong>Piano Nazionale Transizione 4.0 (Industria 4.0)<\/strong>, approvato nella\u00a0Legge di Bilancio 2021, finalizzato a sostenere la ripresa economica e a dare stabilit\u00e0 alle imprese,\u00a0accompagnandole nel processo di transizione tecnologica e di sostenibilit\u00e0 ambientale.\u00a0<\/em><\/p>\n<\/div><\/section>\n<section  class='av_textblock_section av-lnn49dhn-3a476a1bdd48df255078937c9719c474 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>La tecnologia DIGAMA non si ferma! Ecco in azione il nuovo ROBOT ANTROPOMORFO per la Pallettizzazione di scatole. Grazie alla testa di carico aspirante \u00e8 possibile pallettizzare anche i cartoni o le buste pi\u00f9 fragili. Con Meccanica DIGAMA il carico \u00e8 veloce e al sicuro!<\/p>\n<\/div><\/section>\n<div  class='hr av-4mdtwm-f1fdc06282fa2ee01076948e4091612f hr-default  avia-builder-el-4  el_after_av_textblock  el_before_av_textblock '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n<section  class='av_textblock_section av-23dq3a-6e966ec04d94d4908ffdf36492b29e3a '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" >\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f402-o1\" lang=\"it-IT\" dir=\"ltr\" data-wpcf7-id=\"402\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/it\/wp-json\/wp\/v2\/pages\/1647#wpcf7-f402-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Modulo di contatto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"402\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.3\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"it_IT\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f402-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<h2 class=\"head-form\">Personalizza il macchinario secondo le tue esigenze.<br \/>\nContattaci!\n<\/h2>\n<p><span id=\"wpcf7-6a04c5d360197-wrapper\" class=\"wpcf7-form-control-wrap azienda-wrap\" style=\"display:none !important; visibility:hidden !important;\"><label for=\"azienda\" class=\"hp-message\">Si prega di lasciare vuoto questo campo.<\/label><input id=\"azienda\"  class=\"wpcf7-form-control wpcf7-text\" type=\"text\" name=\"azienda\" value=\"\" size=\"40\" tabindex=\"-1\" autocomplete=\"new-password\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nome\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-surname\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"surname\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Cognome\" value=\"\" type=\"text\" name=\"your-surname\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-tel\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Telefono\" value=\"\" type=\"tel\" name=\"your-tel\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Il tuo messaggio\" name=\"your-message\"><\/textarea><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-152\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"acceptance-152\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">Dichiaro di aver letto attentamente e compreso il contenuto della\u00a0<a href=\"\/privacy-policy\/\" target=\"_blank\" rel=\"noopener\">Privacy Policy<\/a>\u00a0relativamente alle finalit\u00e0 perseguite tramite l'acquisizione dei dati personali necessari all\u2019esecuzione delle prestazioni oggetto del servizio erogato.<\/span><\/label><\/span><\/span><\/span>\n<\/p>\n<p><input type=\"hidden\" name=\"_wpcf7_captcha_challenge_captcha-1\" value=\"3665954130\" \/><img loading=\"lazy\" decoding=\"async\" class=\"wpcf7-form-control wpcf7-captchac wpcf7-captcha-captcha-1\" width=\"72\" height=\"24\" alt=\"captcha\" src=\"https:\/\/www.meccanicadigama.com\/wp-content\/uploads\/wpcf7_captcha\/3665954130.png\" \/><span class=\"wpcf7-form-control-wrap\" data-name=\"captcha-1\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-captchar\" autocomplete=\"off\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"captcha-1\" \/><\/span><br \/>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" id=\"sendform\" type=\"submit\" value=\"Contattaci\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n<\/div><\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1647","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Robot Pallettizzatore con testata aspirante - Robot - Meccanica Digama<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.meccanicadigama.com\/it\/robot-pallettizzatore-con-testata-aspirante\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Robot Pallettizzatore con testata aspirante - Robot - Meccanica Digama\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.meccanicadigama.com\/it\/robot-pallettizzatore-con-testata-aspirante\/\" \/>\n<meta property=\"og:site_name\" content=\"Meccanica Digama\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-20T07:33:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.meccanicadigama.com\/it\/robot-pallettizzatore-con-testata-aspirante\/\",\"url\":\"https:\/\/www.meccanicadigama.com\/it\/robot-pallettizzatore-con-testata-aspirante\/\",\"name\":\"Robot Pallettizzatore con testata aspirante - Robot - Meccanica Digama\",\"isPartOf\":{\"@id\":\"https:\/\/www.meccanicadigama.com\/it\/#website\"},\"datePublished\":\"2023-10-12T11:50:06+00:00\",\"dateModified\":\"2023-10-20T07:33:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.meccanicadigama.com\/it\/robot-pallettizzatore-con-testata-aspirante\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.meccanicadigama.com\/it\/robot-pallettizzatore-con-testata-aspirante\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.meccanicadigama.com\/it\/robot-pallettizzatore-con-testata-aspirante\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.meccanicadigama.com\/it\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Robot Pallettizzatore con testata aspirante &#8211; Robot\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.meccanicadigama.com\/it\/#website\",\"url\":\"https:\/\/www.meccanicadigama.com\/it\/\",\"name\":\"Meccanica Digama\",\"description\":\"Macchine per l&#039;industria alimentare\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.meccanicadigama.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Robot Pallettizzatore con testata aspirante - Robot - Meccanica Digama","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.meccanicadigama.com\/it\/robot-pallettizzatore-con-testata-aspirante\/","og_locale":"it_IT","og_type":"article","og_title":"Robot Pallettizzatore con testata aspirante - Robot - Meccanica Digama","og_url":"https:\/\/www.meccanicadigama.com\/it\/robot-pallettizzatore-con-testata-aspirante\/","og_site_name":"Meccanica Digama","article_modified_time":"2023-10-20T07:33:56+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"12 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.meccanicadigama.com\/it\/robot-pallettizzatore-con-testata-aspirante\/","url":"https:\/\/www.meccanicadigama.com\/it\/robot-pallettizzatore-con-testata-aspirante\/","name":"Robot Pallettizzatore con testata aspirante - Robot - Meccanica Digama","isPartOf":{"@id":"https:\/\/www.meccanicadigama.com\/it\/#website"},"datePublished":"2023-10-12T11:50:06+00:00","dateModified":"2023-10-20T07:33:56+00:00","breadcrumb":{"@id":"https:\/\/www.meccanicadigama.com\/it\/robot-pallettizzatore-con-testata-aspirante\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.meccanicadigama.com\/it\/robot-pallettizzatore-con-testata-aspirante\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.meccanicadigama.com\/it\/robot-pallettizzatore-con-testata-aspirante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.meccanicadigama.com\/it\/home\/"},{"@type":"ListItem","position":2,"name":"Robot Pallettizzatore con testata aspirante &#8211; Robot"}]},{"@type":"WebSite","@id":"https:\/\/www.meccanicadigama.com\/it\/#website","url":"https:\/\/www.meccanicadigama.com\/it\/","name":"Meccanica Digama","description":"Macchine per l&#039;industria alimentare","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.meccanicadigama.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.meccanicadigama.com\/it\/wp-json\/wp\/v2\/pages\/1647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.meccanicadigama.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.meccanicadigama.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.meccanicadigama.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.meccanicadigama.com\/it\/wp-json\/wp\/v2\/comments?post=1647"}],"version-history":[{"count":6,"href":"https:\/\/www.meccanicadigama.com\/it\/wp-json\/wp\/v2\/pages\/1647\/revisions"}],"predecessor-version":[{"id":3054,"href":"https:\/\/www.meccanicadigama.com\/it\/wp-json\/wp\/v2\/pages\/1647\/revisions\/3054"}],"wp:attachment":[{"href":"https:\/\/www.meccanicadigama.com\/it\/wp-json\/wp\/v2\/media?parent=1647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}